{"id":98,"count":23,"description":"","link":"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/rpg\/","name":"RPG","slug":"rpg","taxonomy":"category","parent":48,"meta":[],"acf":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Alle Beitr\u00e4ge zur Kategorie &quot;RPG&quot; | SpieleCheck ver\u00f6ffentlicht Game Reviews und News zu PC-Spielen auf eigenen Kan\u00e4len.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"vd9Fp4EPjxdabCEJreHeRT6FIgd7FLeKQsQt0qUR-AA\" \/>\n\t<meta name=\"p:domain_verify\" content=\"0549fc0b792c03b59db142166b471c53\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/rpg\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"nl_NL\" \/>\n\t\t<meta property=\"og:site_name\" content=\"SPIELECHECK\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"RPG | SPIELECHECK\" \/>\n\t\t<meta property=\"og:description\" content=\"Alle Beitr\u00e4ge zur Kategorie &quot;RPG&quot; | SpieleCheck ver\u00f6ffentlicht Game Reviews und News zu PC-Spielen auf eigenen Kan\u00e4len.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/rpg\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/spielecheck.gg\/wp-content\/uploads\/2024\/11\/seo-picture-spielecheck-01.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/spielecheck.gg\/wp-content\/uploads\/2024\/11\/seo-picture-spielecheck-01.webp\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/spielecheckgg\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@SpieleCheckGG\" \/>\n\t\t<meta name=\"twitter:title\" content=\"RPG | SPIELECHECK\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Alle Beitr\u00e4ge zur Kategorie &quot;RPG&quot; | SpieleCheck ver\u00f6ffentlicht Game Reviews und News zu PC-Spielen auf eigenen Kan\u00e4len.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/spielecheck.gg\/wp-content\/uploads\/2024\/11\/seo-picture-spielecheck-01.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/98\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl#listItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/spelletjes\\\/#listItem\",\"name\":\"Games\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/spelletjes\\\/#listItem\",\"position\":2,\"name\":\"Games\",\"item\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/spelletjes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/spelletjes\\\/rpg\\\/#listItem\",\"name\":\"RPG\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl#listItem\",\"name\":\"Start\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/spelletjes\\\/rpg\\\/#listItem\",\"position\":3,\"name\":\"RPG\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/spelletjes\\\/#listItem\",\"name\":\"Games\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/98\\\/#collectionpage\",\"url\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/98\\\/\",\"name\":\"RPG | SPIELECHECK\",\"description\":\"Alle Beitr\\u00e4ge zur Kategorie \\\"RPG\\\" | SpieleCheck ver\\u00f6ffentlicht Game Reviews und News zu PC-Spielen auf eigenen Kan\\u00e4len.\",\"inLanguage\":\"nl-NL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/98\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/#organization\",\"name\":\"SPIELECHECK\",\"description\":\"Independent Gaming Magazin\",\"url\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/\",\"email\":\"look@spielecheck.gg\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/spielecheck.gg\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/spielecheck-logo-2024-01.png\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/98\\\/#organizationLogo\",\"width\":1284,\"height\":232,\"caption\":\"SPIELECHECK\"},\"image\":{\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/98\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/spielecheckgg\\\/\",\"https:\\\/\\\/x.com\\\/SpieleCheckGG\",\"https:\\\/\\\/www.instagram.com\\\/spielecheck\",\"https:\\\/\\\/www.tiktok.com\\\/@spielecheckgg\",\"https:\\\/\\\/www.youtube.com\\\/@spielecheckgg\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/spielecheck\\\/\",\"https:\\\/\\\/bsky.app\\\/profile\\\/spielecheck.bsky.social\",\"https:\\\/\\\/www.threads.com\\\/@spielecheck\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/#website\",\"url\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/\",\"name\":\"SPIELECHECK\",\"description\":\"Independent Gaming Magazin\",\"inLanguage\":\"nl-NL\",\"publisher\":{\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>RPG | SPIELECHECK<\/title>\n\n","aioseo_head_json":{"title":"RPG | SPIELECHECK","description":"Alle artikelen in de categorie \"RPG\" | SpieleCheck publiceert recensies van spellen en nieuws over PC-spellen op zijn eigen kanalen.","canonical_url":"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/rpg\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"vd9Fp4EPjxdabCEJreHeRT6FIgd7FLeKQsQt0qUR-AA","p:domain_verify":"0549fc0b792c03b59db142166b471c53","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/spielecheck.gg\/nl-nl\/wp-json\/wp\/v2\/categories\/98\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/spielecheck.gg\/nl-nl#listItem","position":1,"name":"Start","item":"https:\/\/spielecheck.gg\/nl-nl","nextItem":{"@type":"ListItem","@id":"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/#listItem","name":"Games"}},{"@type":"ListItem","@id":"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/#listItem","position":2,"name":"Games","item":"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/rpg\/#listItem","name":"RPG"},"previousItem":{"@type":"ListItem","@id":"https:\/\/spielecheck.gg\/nl-nl#listItem","name":"Start"}},{"@type":"ListItem","@id":"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/rpg\/#listItem","position":3,"name":"RPG","previousItem":{"@type":"ListItem","@id":"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/#listItem","name":"Games"}}]},{"@type":"CollectionPage","@id":"https:\/\/spielecheck.gg\/nl-nl\/wp-json\/wp\/v2\/categories\/98\/#collectionpage","url":"https:\/\/spielecheck.gg\/nl-nl\/wp-json\/wp\/v2\/categories\/98\/","name":"RPG | SPIELECHECK","description":"Alle Beitr\u00e4ge zur Kategorie \"RPG\" | SpieleCheck ver\u00f6ffentlicht Game Reviews und News zu PC-Spielen auf eigenen Kan\u00e4len.","inLanguage":"nl-NL","isPartOf":{"@id":"https:\/\/spielecheck.gg\/nl-nl\/#website"},"breadcrumb":{"@id":"https:\/\/spielecheck.gg\/nl-nl\/wp-json\/wp\/v2\/categories\/98\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/spielecheck.gg\/nl-nl\/#organization","name":"SPIELECHECK","description":"Independent Gaming Magazin","url":"https:\/\/spielecheck.gg\/nl-nl\/","email":"look@spielecheck.gg","logo":{"@type":"ImageObject","url":"https:\/\/spielecheck.gg\/wp-content\/uploads\/2024\/11\/spielecheck-logo-2024-01.png","@id":"https:\/\/spielecheck.gg\/nl-nl\/wp-json\/wp\/v2\/categories\/98\/#organizationLogo","width":1284,"height":232,"caption":"SPIELECHECK"},"image":{"@id":"https:\/\/spielecheck.gg\/nl-nl\/wp-json\/wp\/v2\/categories\/98\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/spielecheckgg\/","https:\/\/x.com\/SpieleCheckGG","https:\/\/www.instagram.com\/spielecheck","https:\/\/www.tiktok.com\/@spielecheckgg","https:\/\/www.youtube.com\/@spielecheckgg\/","https:\/\/www.linkedin.com\/company\/spielecheck\/","https:\/\/bsky.app\/profile\/spielecheck.bsky.social","https:\/\/www.threads.com\/@spielecheck"]},{"@type":"WebSite","@id":"https:\/\/spielecheck.gg\/nl-nl\/#website","url":"https:\/\/spielecheck.gg\/nl-nl\/","name":"SPIELECHECK","description":"Independent Gaming Magazin","inLanguage":"nl-NL","publisher":{"@id":"https:\/\/spielecheck.gg\/nl-nl\/#organization"}}]},"og:locale":"nl_NL","og:site_name":"SPIELECHECK","og:type":"article","og:title":"RPG | SPIELECHECK","og:description":"Alle Beitr\u00e4ge zur Kategorie &quot;RPG&quot; | SpieleCheck ver\u00f6ffentlicht Game Reviews und News zu PC-Spielen auf eigenen Kan\u00e4len.","og:url":"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/rpg\/","og:image":"https:\/\/spielecheck.gg\/wp-content\/uploads\/2024\/11\/seo-picture-spielecheck-01.webp","og:image:secure_url":"https:\/\/spielecheck.gg\/wp-content\/uploads\/2024\/11\/seo-picture-spielecheck-01.webp","og:image:width":1280,"og:image:height":720,"article:publisher":"https:\/\/www.facebook.com\/spielecheckgg\/","twitter:card":"summary_large_image","twitter:site":"@SpieleCheckGG","twitter:title":"RPG | SPIELECHECK","twitter:description":"Alle Beitr\u00e4ge zur Kategorie &quot;RPG&quot; | SpieleCheck ver\u00f6ffentlicht Game Reviews und News zu PC-Spielen auf eigenen Kan\u00e4len.","twitter:image":"https:\/\/spielecheck.gg\/wp-content\/uploads\/2024\/11\/seo-picture-spielecheck-01.webp"},"aioseo_meta_data":{"term_id":"98","title":null,"description":null,"keywords":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_custom_image_width":null,"og_custom_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"tabs":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-12 20:47:15","breadcrumb_settings":null,"created":"2025-08-14 20:52:20","updated":"2026-05-12 20:47:15","og_image_url":null,"og_image_width":null,"og_image_height":null,"twitter_image_url":null,"pillar_content":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/spielecheck.gg\/nl-nl\" title=\"Start\">Start<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/\" title=\"Games\">Games<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/rpg\/\" title=\"RPG\">RPG<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Start","link":"https:\/\/spielecheck.gg\/nl-nl"},{"label":"Games","link":"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/"},{"label":"RPG","link":"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/rpg\/"}],"_links":{"self":[{"href":"https:\/\/spielecheck.gg\/nl-nl\/wp-json\/wp\/v2\/categories\/98","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spielecheck.gg\/nl-nl\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/spielecheck.gg\/nl-nl\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/spielecheck.gg\/nl-nl\/wp-json\/wp\/v2\/categories\/48"}],"wp:post_type":[{"href":"https:\/\/spielecheck.gg\/nl-nl\/wp-json\/wp\/v2\/posts?categories=98"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}