{"id":11472,"date":"2023-04-17T22:34:06","date_gmt":"2023-04-17T20:34:06","guid":{"rendered":"https:\/\/spielecheck.gg\/?p=11472"},"modified":"2023-06-12T16:37:16","modified_gmt":"2023-06-12T14:37:16","slug":"arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie","status":"publish","type":"post","link":"https:\/\/spielecheck.gg\/nl-nl\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\/","title":{"rendered":"Arbeiders &amp; Middelen: Sovjetrepubliek - Met karton en plaatmetaal naar een planeconomie"},"content":{"rendered":"<p><strong>Workers &amp; Resources: Soviet Republic is een bouwsimulatiespel dat spelers meeneemt naar de tijd van de Sovjet-Unie. In de rol van een burgemeester die een arme Sovjetrepubliek moet omvormen tot een machtige industri\u00eble natie, moeten alle aspecten van de planeconomie onder de knie worden gekregen. De taken vari\u00ebren van de aanschaf van grondstoffen tot de ontwikkeling van industrie en infrastructuur voor de welvaart van de burgers.<\/strong><\/p>\n<h2>Beheer van verkeer en vervoer<\/h2>\n<p>Een van de belangrijkste taken in Workers &amp; Resources: Sovjetrepubliek is een <a href=\"https:\/\/spielecheck.gg\/nl-nl\/het-zwervende-dorpsleven-op-de-rug-van-een-wonderlijk-wezen\/\">Effici\u00ebnt transportbeheer<\/a>. Grondstoffen en goederen moeten worden vervoerd tussen verschillende locaties zoals mijnen, fabrieken en woonwijken. Hiervoor zijn verschillende transportmiddelen beschikbaar, zoals treinen, transportbanden en vrachtwagens. Vanaf het begin moet worden besloten of de infrastructuur zodanig moet worden ontwikkeld dat de <a href=\"https:\/\/spielecheck.gg\/nl-nl\/recept-voor-ramp-koken-collegas-rampen\/\">Werknemers in de buurt<\/a> van hun werkplek, of dat ze met bus en trein naar de industriegebieden worden vervoerd.<\/p>\n<figure id=\"attachment_11479\" aria-describedby=\"caption-attachment-11479\" style=\"width: 1280px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-11479 size-full\" src=\"https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-04.jpg\" alt=\"Arbeiders en hulpbronnen: Sovjetrepubliek\" width=\"1280\" height=\"720\" srcset=\"https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-04.jpg 1280w, https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-04-300x169.jpg 300w, https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-04-1024x576.jpg 1024w, https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-04-768x432.jpg 768w, https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-04-150x84.jpg 150w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><figcaption id=\"caption-attachment-11479\" class=\"wp-caption-text\">Hoe groter een stad is, hoe meer de transportroutes met elkaar verbonden zijn.<\/figcaption><\/figure>\n<h2>Grondstoffen en industri\u00eble complexen als kern in Workers &amp; Resources: Sovjetrepubliek<\/h2>\n<p>Het spel biedt meer dan 30 verschillende grondstoffen die kunnen worden gedolven, getransporteerd en verwerkt. Om bijvoorbeeld kleding te maken, moet je eerst stoffen produceren en vervolgens een kledingfabriek bouwen. <a href=\"https:\/\/spielecheck.gg\/nl-nl\/slimme-fabriek-tycoon-lopende-band-werk-en-machines\/\">De afgewerkte producten<\/a> kunnen dan worden verkocht in winkels om <a href=\"https:\/\/spielecheck.gg\/nl-nl\/the-universim-in-het-leven-geschapen-met-goddelijke-hand\/\">Behoeften van burgers<\/a> te dekken. Elk product heeft specifieke vereisten voor opslag en transport waarmee rekening moet worden gehouden.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-11477\" src=\"https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-02.jpg\" alt=\"Arbeiders en hulpbronnen: Sovjetrepubliek\" width=\"800\" height=\"888\" srcset=\"https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-02.jpg 800w, https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-02-270x300.jpg 270w, https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-02-768x852.jpg 768w, https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-02-150x167.jpg 150w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<h2>Werknemers en hun behoeften<\/h2>\n<p>Het welzijn van de burgers is doorslaggevend voor het succes van de Sovjetrepubliek. Elke arbeider heeft <a href=\"https:\/\/spielecheck.gg\/nl-nl\/autokerkhof-simulator-heet-of-schroot\/\">Individuele behoeften<\/a>die in de loop van de tijd groeien. Aanvankelijk zijn ze alleen tevreden met voedsel, later eisen ze kleding, alcohol en elektronica. Om op de lange termijn succesvol te zijn, moet ervoor gezorgd worden dat burgers toegang hebben tot onderwijs, <a href=\"https:\/\/spielecheck.gg\/nl-nl\/leven-door-jou-dat-het-leven-in-ongewone-richtingen-stuurt\/\">Vrijetijdsvoorzieningen<\/a> en voedsel om gelukkig en productief te zijn.<\/p>\n<h2>Economische simulatie en toenemende complexiteit<\/h2>\n<p>Arbeiders en middelen: Sovjetrepubliek simuleert een <a href=\"https:\/\/spielecheck.gg\/nl-nl\/urbek-city-builder-stadsbouwsimulatie-ontmoet-strategisch-middelenbeheer\/\">Realistisch economisch systeem<\/a>waarin prijzen worden bepaald door vraag en aanbod. Het kopen en verkopen van goederen om dollars of roebels te verkrijgen om te investeren in nieuwe infrastructuur en gebouwen staat centraal in de simulatie. Na verloop van tijd wordt het spel steeds complexer en wordt het steeds moeilijker om de economie draaiende te houden.<\/p>\n<figure id=\"attachment_11478\" aria-describedby=\"caption-attachment-11478\" style=\"width: 1280px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"wp-image-11478 size-full\" src=\"https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-03.jpg\" alt=\"Arbeiders en hulpbronnen: Sovjetrepubliek\" width=\"1280\" height=\"720\" srcset=\"https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-03.jpg 1280w, https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-03-300x169.jpg 300w, https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-03-1024x576.jpg 1024w, https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-03-768x432.jpg 768w, https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-03-150x84.jpg 150w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><figcaption id=\"caption-attachment-11478\" class=\"wp-caption-text\">De charme van de jaren 70 en 80 is vastgelegd met veel aandacht voor detail en gepresenteerd in fantastische animaties.<\/figcaption><\/figure>\n<h2>Volle kracht vooruit in Werknemers &amp; Middelen: Sovjetrepubliek<\/h2>\n<p>Arbeiders &amp; Middelen: Sovjetrepubliek is een uitdagende en <a href=\"https:\/\/spielecheck.gg\/nl-nl\/tag\/constructiesimulatie\/\">Gevarieerd opbouwspel<\/a>dat spelers een authentieke socialistische tycoon-ervaring biedt. Met een verscheidenheid aan grondstoffen, <a href=\"https:\/\/spielecheck.gg\/nl-nl\/het-aanhoudende-succes-van-transportmagnaat\/\">Transportopties<\/a> en de groeiende eisen van de burgers, moeten de spelers hun vaardigheden als planners, managers en diplomaten tonen om hun Sovjetrepubliek te ontwikkelen tot een bloeiende ge\u00efndustrialiseerde natie. Ze kunnen ervoor kiezen een zelfvoorzienende economie op te bouwen of handel te drijven met andere landen. Authentieke Sovjetgebouwen, voertuigen en landschappen uit de jaren '60 tot '90 dragen bij aan de sfeer van het spel.<\/p>\n<p>Dankzij de diepgaande economische simulatie en de constant groeiende complexiteit biedt Workers &amp; Resources: Soviet Republic urenlang speelplezier en een echte uitdaging voor fans van strategie en tycoons. Of je nu in <a href=\"https:\/\/spielecheck.gg\/nl-nl\/?s=Sandbox\">Zandbakmodus<\/a> met onbeperkte middelen of in de volledige versie, waarin elk detail telt - het spel biedt een breed scala aan mogelijkheden, <a href=\"https:\/\/www.sovietrepublic.net\/\" target=\"_blank\" rel=\"noopener\">om het socialistische economische paradijs vorm te geven<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Dankzij de diepgaande economische simulatie en de constant groeiende complexiteit biedt Workers &amp; Resources: Soviet Republic urenlang speelplezier en een echte uitdaging voor fans van strategie en tycoons.<\/p>","protected":false},"author":2,"featured_media":11476,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[48,62,74],"tags":[612,463,67,76,611],"class_list":["post-11472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-games","category-simulation","category-strategie","tag-3division","tag-aufbausimulation","tag-simulation","tag-strategie","tag-workers-resources-soviet-republic"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Dank der tiefgreifenden Wirtschaftssimulation bietet Workers &amp; Resources: Soviet Republic stundenlangen Spielspa\u00df und echte Herausforderungen f\u00fcr Tycoon-Fans.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"EinfachTommy\"\/>\n\t<meta name=\"google-site-verification\" content=\"vd9Fp4EPjxdabCEJreHeRT6FIgd7FLeKQsQt0qUR-AA\" \/>\n\t<meta name=\"p:domain_verify\" content=\"0549fc0b792c03b59db142166b471c53\" \/>\n\t<meta name=\"keywords\" content=\"workers &amp; resources: soviet republic,3division,aufbausimulation,strategie,simulation,workers &amp; resources: soviet republic,games\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/spielecheck.gg\/nl-nl\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"nl_NL\" \/>\n\t\t<meta property=\"og:site_name\" content=\"SPIELECHECK\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Workers &amp; Resources: Soviet Republic \u2013 Mit Pappe und Blech zur Planwirtschaft\" \/>\n\t\t<meta property=\"og:description\" content=\"Dank der tiefgreifenden Wirtschaftssimulation bietet Workers &amp; Resources: Soviet Republic stundenlangen Spielspa\u00df und echte Herausforderungen f\u00fcr Tycoon-Fans.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/spielecheck.gg\/nl-nl\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-01.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-01.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t\t<meta property=\"article:tag\" content=\"strategie\" \/>\n\t\t<meta property=\"article:tag\" content=\"simulation\" \/>\n\t\t<meta property=\"article:tag\" content=\"workers &amp; resources: soviet republic\" \/>\n\t\t<meta property=\"article:tag\" content=\"3division\" \/>\n\t\t<meta property=\"article:tag\" content=\"workers &amp; resources: soviet republic\" \/>\n\t\t<meta property=\"article:tag\" content=\"aufbausimulation\" \/>\n\t\t<meta property=\"article:tag\" content=\"games\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-04-17T20:34:06+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-06-12T14:37:16+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/spielecheckgg\/\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/31nf4ch70mmy.D3\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@SpieleCheckGG\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Workers &amp; Resources: Soviet Republic - Russisch Tycoon\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Dank der tiefgreifenden Wirtschaftssimulation bietet Workers &amp; Resources: Soviet Republic stundenlangen Spielspa\u00df und echte Herausforderungen f\u00fcr Tycoon-Fans.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@EinfachTommyDE\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-01.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"EinfachTommy\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minuten\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\\\/#article\",\"name\":\"Workers & Resources: Soviet Republic - Russisch Tycoon\",\"headline\":\"Workers &#038; Resources: Soviet Republic &#8211; Mit Pappe und Blech zur Planwirtschaft\",\"author\":{\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/author\\\/einfachtommy\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/spielecheck.gg\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-01.jpg\",\"width\":1280,\"height\":720},\"datePublished\":\"2023-04-17T22:34:06+02:00\",\"dateModified\":\"2023-06-12T16:37:16+02:00\",\"inLanguage\":\"nl-NL\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\\\/#webpage\"},\"articleSection\":\"Games, Simulation, Strategie, 3Division, Aufbausimulation, Simulation, Strategie, Workers &amp; Resources: Soviet Republic\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl#listItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/spelletjes\\\/#listItem\",\"name\":\"Games\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/spelletjes\\\/#listItem\",\"position\":2,\"name\":\"Games\",\"item\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/spelletjes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/spelletjes\\\/simulatie\\\/#listItem\",\"name\":\"Simulation\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl#listItem\",\"name\":\"Start\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/spelletjes\\\/simulatie\\\/#listItem\",\"position\":3,\"name\":\"Simulation\",\"item\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/spelletjes\\\/simulatie\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\\\/#listItem\",\"name\":\"Workers &#038; Resources: Soviet Republic &#8211; Mit Pappe und Blech zur Planwirtschaft\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/spelletjes\\\/#listItem\",\"name\":\"Games\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\\\/#listItem\",\"position\":4,\"name\":\"Workers &#038; Resources: Soviet Republic &#8211; Mit Pappe und Blech zur Planwirtschaft\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/spelletjes\\\/simulatie\\\/#listItem\",\"name\":\"Simulation\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/#organization\",\"name\":\"SPIELECHECK\",\"description\":\"Independent Gaming Magazin\",\"url\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/\",\"email\":\"look@spielecheck.gg\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/spielecheck.gg\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/spielecheck-logo-2024-01.png\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\\\/#organizationLogo\",\"width\":1284,\"height\":232,\"caption\":\"SPIELECHECK\"},\"image\":{\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/spielecheckgg\\\/\",\"https:\\\/\\\/x.com\\\/SpieleCheckGG\",\"https:\\\/\\\/www.instagram.com\\\/spielecheck\",\"https:\\\/\\\/www.tiktok.com\\\/@spielecheckgg\",\"https:\\\/\\\/www.youtube.com\\\/@spielecheckgg\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/spielecheck\\\/\",\"https:\\\/\\\/bsky.app\\\/profile\\\/spielecheck.bsky.social\",\"https:\\\/\\\/www.threads.com\\\/@spielecheck\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/author\\\/einfachtommy\\\/#author\",\"url\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/author\\\/einfachtommy\\\/\",\"name\":\"EinfachTommy\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/31nf4ch70mmy.D3\",\"https:\\\/\\\/twitter.com\\\/EinfachTommyDE\",\"https:\\\/\\\/www.instagram.com\\\/einfachtommy.de\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@einfachtommyde\",\"https:\\\/\\\/www.pinterest.de\\\/einfachtommyde\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCKW3b8dFvFQQYvfg7GR2n1w\",\"https:\\\/\\\/www.twitch.tv\\\/einfachtommyde\",\"https:\\\/\\\/mastodon.social\\\/@EinfachTommy\"],\"jobTitle\":\"Gr\\u00fcnder von SPIELECHECK und Autor\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/spielecheck.gg\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/tommy-400x400-1.jpg\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\\\/#webpage\",\"url\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\\\/\",\"name\":\"Workers & Resources: Soviet Republic - Russisch Tycoon\",\"description\":\"Dank der tiefgreifenden Wirtschaftssimulation bietet Workers & Resources: Soviet Republic stundenlangen Spielspa\\u00df und echte Herausforderungen f\\u00fcr Tycoon-Fans.\",\"inLanguage\":\"nl-NL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/author\\\/einfachtommy\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/author\\\/einfachtommy\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/spielecheck.gg\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-01.jpg\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\\\/#mainImage\",\"width\":1280,\"height\":720},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\\\/#mainImage\"},\"datePublished\":\"2023-04-17T22:34:06+02:00\",\"dateModified\":\"2023-06-12T16:37:16+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/#website\",\"url\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/\",\"name\":\"SPIELECHECK\",\"description\":\"Independent Gaming Magazin\",\"inLanguage\":\"nl-NL\",\"publisher\":{\"@id\":\"https:\\\/\\\/spielecheck.gg\\\/nl-nl\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Workers &amp; Resources: Soviet Republic - Russisch Tycoon<\/title>\n\n","aioseo_head_json":{"title":"Arbeiders &amp; Middelen: Sovjetrepubliek - Russische Tycoon","description":"Dankzij de diepgaande economische simulatie biedt Workers &amp; Resources: Soviet Republic urenlang speelplezier en echte uitdagingen voor tycoonfans.","canonical_url":"https:\/\/spielecheck.gg\/nl-nl\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\/","robots":"max-image-preview:large","keywords":"workers &amp; resources: soviet republic,3division,aufbausimulation,strategie,simulation,workers &amp; resources: soviet republic,games","webmasterTools":{"google-site-verification":"vd9Fp4EPjxdabCEJreHeRT6FIgd7FLeKQsQt0qUR-AA","p:domain_verify":"0549fc0b792c03b59db142166b471c53","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spielecheck.gg\/nl-nl\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\/#article","name":"Workers & Resources: Soviet Republic - Russisch Tycoon","headline":"Workers &#038; Resources: Soviet Republic &#8211; Mit Pappe und Blech zur Planwirtschaft","author":{"@id":"https:\/\/spielecheck.gg\/nl-nl\/author\/einfachtommy\/#author"},"publisher":{"@id":"https:\/\/spielecheck.gg\/nl-nl\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-01.jpg","width":1280,"height":720},"datePublished":"2023-04-17T22:34:06+02:00","dateModified":"2023-06-12T16:37:16+02:00","inLanguage":"nl-NL","mainEntityOfPage":{"@id":"https:\/\/spielecheck.gg\/nl-nl\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\/#webpage"},"isPartOf":{"@id":"https:\/\/spielecheck.gg\/nl-nl\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\/#webpage"},"articleSection":"Games, Simulation, Strategie, 3Division, Aufbausimulation, Simulation, Strategie, Workers &amp; Resources: Soviet Republic"},{"@type":"BreadcrumbList","@id":"https:\/\/spielecheck.gg\/nl-nl\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/spielecheck.gg\/nl-nl#listItem","position":1,"name":"Start","item":"https:\/\/spielecheck.gg\/nl-nl","nextItem":{"@type":"ListItem","@id":"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/#listItem","name":"Games"}},{"@type":"ListItem","@id":"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/#listItem","position":2,"name":"Games","item":"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/simulatie\/#listItem","name":"Simulation"},"previousItem":{"@type":"ListItem","@id":"https:\/\/spielecheck.gg\/nl-nl#listItem","name":"Start"}},{"@type":"ListItem","@id":"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/simulatie\/#listItem","position":3,"name":"Simulation","item":"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/simulatie\/","nextItem":{"@type":"ListItem","@id":"https:\/\/spielecheck.gg\/nl-nl\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\/#listItem","name":"Workers &#038; Resources: Soviet Republic &#8211; Mit Pappe und Blech zur Planwirtschaft"},"previousItem":{"@type":"ListItem","@id":"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/#listItem","name":"Games"}},{"@type":"ListItem","@id":"https:\/\/spielecheck.gg\/nl-nl\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\/#listItem","position":4,"name":"Workers &#038; Resources: Soviet Republic &#8211; Mit Pappe und Blech zur Planwirtschaft","previousItem":{"@type":"ListItem","@id":"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/simulatie\/#listItem","name":"Simulation"}}]},{"@type":"Organization","@id":"https:\/\/spielecheck.gg\/nl-nl\/#organization","name":"SPIELECHECK","description":"Independent Gaming Magazin","url":"https:\/\/spielecheck.gg\/nl-nl\/","email":"look@spielecheck.gg","logo":{"@type":"ImageObject","url":"https:\/\/spielecheck.gg\/wp-content\/uploads\/2024\/11\/spielecheck-logo-2024-01.png","@id":"https:\/\/spielecheck.gg\/nl-nl\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\/#organizationLogo","width":1284,"height":232,"caption":"SPIELECHECK"},"image":{"@id":"https:\/\/spielecheck.gg\/nl-nl\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/spielecheckgg\/","https:\/\/x.com\/SpieleCheckGG","https:\/\/www.instagram.com\/spielecheck","https:\/\/www.tiktok.com\/@spielecheckgg","https:\/\/www.youtube.com\/@spielecheckgg\/","https:\/\/www.linkedin.com\/company\/spielecheck\/","https:\/\/bsky.app\/profile\/spielecheck.bsky.social","https:\/\/www.threads.com\/@spielecheck"]},{"@type":"Person","@id":"https:\/\/spielecheck.gg\/nl-nl\/author\/einfachtommy\/#author","url":"https:\/\/spielecheck.gg\/nl-nl\/author\/einfachtommy\/","name":"EinfachTommy","sameAs":["https:\/\/www.facebook.com\/31nf4ch70mmy.D3","https:\/\/twitter.com\/EinfachTommyDE","https:\/\/www.instagram.com\/einfachtommy.de\/","https:\/\/www.tiktok.com\/@einfachtommyde","https:\/\/www.pinterest.de\/einfachtommyde\/","https:\/\/www.youtube.com\/channel\/UCKW3b8dFvFQQYvfg7GR2n1w","https:\/\/www.twitch.tv\/einfachtommyde","https:\/\/mastodon.social\/@EinfachTommy"],"jobTitle":"Gr\u00fcnder von SPIELECHECK und Autor","image":{"@type":"ImageObject","url":"https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/03\/tommy-400x400-1.jpg"}},{"@type":"WebPage","@id":"https:\/\/spielecheck.gg\/nl-nl\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\/#webpage","url":"https:\/\/spielecheck.gg\/nl-nl\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\/","name":"Workers & Resources: Soviet Republic - Russisch Tycoon","description":"Dank der tiefgreifenden Wirtschaftssimulation bietet Workers & Resources: Soviet Republic stundenlangen Spielspa\u00df und echte Herausforderungen f\u00fcr Tycoon-Fans.","inLanguage":"nl-NL","isPartOf":{"@id":"https:\/\/spielecheck.gg\/nl-nl\/#website"},"breadcrumb":{"@id":"https:\/\/spielecheck.gg\/nl-nl\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\/#breadcrumblist"},"author":{"@id":"https:\/\/spielecheck.gg\/nl-nl\/author\/einfachtommy\/#author"},"creator":{"@id":"https:\/\/spielecheck.gg\/nl-nl\/author\/einfachtommy\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-01.jpg","@id":"https:\/\/spielecheck.gg\/nl-nl\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\/#mainImage","width":1280,"height":720},"primaryImageOfPage":{"@id":"https:\/\/spielecheck.gg\/nl-nl\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\/#mainImage"},"datePublished":"2023-04-17T22:34:06+02:00","dateModified":"2023-06-12T16:37:16+02:00"},{"@type":"WebSite","@id":"https:\/\/spielecheck.gg\/nl-nl\/#website","url":"https:\/\/spielecheck.gg\/nl-nl\/","name":"SPIELECHECK","description":"Independent Gaming Magazin","inLanguage":"nl-NL","publisher":{"@id":"https:\/\/spielecheck.gg\/nl-nl\/#organization"}}]},"og:locale":"nl_NL","og:site_name":"SPIELECHECK","og:type":"article","og:title":"Workers &amp; Resources: Soviet Republic \u2013 Mit Pappe und Blech zur Planwirtschaft","og:description":"Dank der tiefgreifenden Wirtschaftssimulation bietet Workers &amp; Resources: Soviet Republic stundenlangen Spielspa\u00df und echte Herausforderungen f\u00fcr Tycoon-Fans.","og:url":"https:\/\/spielecheck.gg\/nl-nl\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\/","og:image":"https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-01.jpg","og:image:secure_url":"https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-01.jpg","og:image:width":1280,"og:image:height":720,"article:tag":{"0":"strategie","1":"simulation","2":"workers & resources: soviet republic","3":"3division","4":"workers &amp; resources: soviet republic","6":"aufbausimulation","10":"games"},"article:published_time":"2023-04-17T20:34:06+00:00","article:modified_time":"2023-06-12T14:37:16+00:00","article:publisher":"https:\/\/www.facebook.com\/spielecheckgg\/","article:author":"https:\/\/www.facebook.com\/31nf4ch70mmy.D3","twitter:card":"summary_large_image","twitter:site":"@SpieleCheckGG","twitter:title":"Workers &amp; Resources: Soviet Republic - Russisch Tycoon","twitter:description":"Dank der tiefgreifenden Wirtschaftssimulation bietet Workers &amp; Resources: Soviet Republic stundenlangen Spielspa\u00df und echte Herausforderungen f\u00fcr Tycoon-Fans.","twitter:creator":"@EinfachTommyDE","twitter:image":"https:\/\/spielecheck.gg\/wp-content\/uploads\/2023\/04\/Workers-Resources-Soviet-Republic-EA-Launch-spielecheck-01.jpg","twitter:label1":"Geschreven door","twitter:data1":"EinfachTommy","twitter:label2":"Geschatte leestijd","twitter:data2":"3 minuten"},"aioseo_meta_data":{"post_id":"11472","title":"Arbeiders &amp; Middelen: Sovjetrepubliek - Russische Tycoon","description":"Dankzij de diepgaande economische simulatie biedt Workers &amp; Resources: Soviet Republic urenlang speelplezier en echte uitdagingen voor tycoonfans.","keywords":[{"label":" Workers & Resources: Soviet Republic","value":" Workers & Resources: Soviet Republic"},{"label":"3Division","value":"3Division"},{"label":"Aufbausimulation","value":"Aufbausimulation"},{"label":"Strategie","value":"Strategie"},{"label":"Simulation","value":"Simulation"}],"keyphrases":{"focus":{"keyphrase":"Workers & Resources: Soviet Republic","score":100,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":4},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":"#post_title","og_description":"Dank der tiefgreifenden Wirtschaftssimulation bietet Workers &amp; Resources: Soviet Republic stundenlangen Spielspa\u00df und echte Herausforderungen f\u00fcr Tycoon-Fans.","og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[{"label":"Strategie","value":"Strategie"},{"label":"Simulation","value":"Simulation"},{"label":"Workers & Resources: Soviet Republic","value":"Workers & Resources: Soviet Republic"},{"label":"3Division","value":"3Division"}],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":"Workers &amp; Resources: Soviet Republic - Russisch Tycoon","twitter_description":"Dank der tiefgreifenden Wirtschaftssimulation bietet Workers &amp; Resources: Soviet Republic stundenlangen Spielspa\u00df und echte Herausforderungen f\u00fcr Tycoon-Fans.","schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":0,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-05-12 20:56:24","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2023-04-17 18:11:32","updated":"2026-05-12 20:56:24"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/spielecheck.gg\/nl-nl\" title=\"Start\">Start<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/\" title=\"Games\">Games<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/simulatie\/\" title=\"Simulation\">Simulation<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/spielecheck.gg\/nl-nl\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\/\" title=\"Workers &amp; Resources: Soviet Republic \u2013 Mit Pappe und Blech zur Planwirtschaft\">Workers &amp; Resources: Soviet Republic \u2013 Mit Pappe und Blech zur Planwirtschaft<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Start","link":"https:\/\/spielecheck.gg\/nl-nl"},{"label":"Games","link":"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/"},{"label":"Simulation","link":"https:\/\/spielecheck.gg\/nl-nl\/spelletjes\/simulatie\/"},{"label":"Workers &#038; Resources: Soviet Republic &#8211; Mit Pappe und Blech zur Planwirtschaft","link":"https:\/\/spielecheck.gg\/nl-nl\/arbeiders-middelen-sovjetrepubliek-met-karton-en-plaatmetaal-naar-een-planeconomie\/"}],"essb_shorturl_ssu":null,"hashtags_social_media":"#Review #sovietrepublic #3Division #Indie #Simulation","_hashtags_social_media":"field_609c2e375f8e9","instagram_carousel_01_feature_url":"","_instagram_carousel_01_feature_url":"field_6486114e56857","instagram_carousel_02_url":"","_instagram_carousel_02_url":"field_6486139756858","instagram_carousel_03_url":"","_instagram_carousel_03_url":"field_648613ee56859","instagram_carousel_04_url":"","_instagram_carousel_04_url":"field_648613f05685a","Instagram_User":null,"_Instagram_User":null,"X_User":null,"_X_User":null,"Facebook_User":null,"_Facebook_User":null,"werbung_hinweis_social_media":"","_werbung_hinweis_social_media":"field_632b8fdc12930","auto_share_make_com":null,"_auto_share_make_com":null,"wp-worthy-pixel":{"ignored":false,"public":"fa9e49b9d91e4eaead2b90f356402d70","server":"vg09.met.vgwort.de","url":"https:\/\/vg09.met.vgwort.de\/na\/fa9e49b9d91e4eaead2b90f356402d70"},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/spielecheck.gg\/nl-nl\/wp-json\/wp\/v2\/posts\/11472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spielecheck.gg\/nl-nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spielecheck.gg\/nl-nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spielecheck.gg\/nl-nl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/spielecheck.gg\/nl-nl\/wp-json\/wp\/v2\/comments?post=11472"}],"version-history":[{"count":0,"href":"https:\/\/spielecheck.gg\/nl-nl\/wp-json\/wp\/v2\/posts\/11472\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spielecheck.gg\/nl-nl\/wp-json\/wp\/v2\/media\/11476"}],"wp:attachment":[{"href":"https:\/\/spielecheck.gg\/nl-nl\/wp-json\/wp\/v2\/media?parent=11472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spielecheck.gg\/nl-nl\/wp-json\/wp\/v2\/categories?post=11472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spielecheck.gg\/nl-nl\/wp-json\/wp\/v2\/tags?post=11472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}